{"id":66,"date":"2015-02-17T21:26:40","date_gmt":"2015-02-17T21:26:40","guid":{"rendered":"https:\/\/themify.me\/demo\/themes\/landing\/?page_id=2894"},"modified":"2020-11-03T10:56:14","modified_gmt":"2020-11-03T09:56:14","slug":"all-layouts","status":"publish","type":"page","link":"https:\/\/rivierasun-properties.com\/index.php\/blog\/all-layouts\/","title":{"rendered":"Post Layouts"},"content":{"rendered":"<div id=\"themify_builder_content-66\" data-postid=\"66\" class=\"themify_builder_content themify_builder_content-66 themify_builder\">\n    \t<!-- module_row -->\n\t<div   data-anchor=\"tiles\" class=\"themify_builder_row module_row clearfix repeat tb_section-tiles module_row_0 themify_builder_66_row module_row_66-0 tb_f93e8a1\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-0-0 tb_4505a7a\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_2267455  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Auto Tiles<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_1420e73 \">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  auto_tiles\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-800x600.jpg\" width=\"800\" height=\"600\" class=\" wp-post-image wp-image-189\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-800x600.jpg 800w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-300x225.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-768x576.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-365x273.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-265x198.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-430x322.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-370x277.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-8\" class=\"post clearfix post-8 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\" aria-label=\"Slider Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-800x600.jpg\" width=\"800\" height=\"600\" class=\" wp-post-image wp-image-187\" alt=\"\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\">Slider Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-9\" class=\"post clearfix post-9 type-post status-publish format-standard has-post-thumbnail hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\" aria-label=\"Split Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-800x600.jpg\" width=\"800\" height=\"600\" class=\" wp-post-image wp-image-188\" alt=\"\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\">Split Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-10\" class=\"post clearfix post-10 type-post status-publish format-standard has-post-thumbnail hentry category-view has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-5\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\" aria-label=\"Fullwidth Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-800x600.jpg\" width=\"800\" height=\"600\" class=\" wp-post-image wp-image-190\" alt=\"\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-04-26\">\n\t\t\t\t\t<span class=\"year\">April 26, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\">Fullwidth Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-11\" class=\"post clearfix post-11 type-post status-publish format-standard has-post-thumbnail hentry category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\" aria-label=\"Left Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-800x600.jpg\" width=\"800\" height=\"600\" class=\" wp-post-image wp-image-191\" alt=\"\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\">Left Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"list-post\" class=\"themify_builder_row module_row clearfix repeat tb_section-list-post module_row_1 themify_builder_66_row module_row_66-1 tb_70a9797\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-1-0 tb_25c5937\" >\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_a3d550f  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>List Post<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_f91e62a \">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  list-post\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\t<p>ztest003-post.&#8212;Text content<\/p>\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"flip\" class=\"themify_builder_row module_row clearfix repeat tb_section-flip module_row_2 themify_builder_66_row module_row_66-2 tb_52a0204\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-2-0 tb_b88b60c\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_352af8e  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Flip Grid4<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_1617f32 \">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  grid4 flip no-gutter masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-189\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-8\" class=\"post clearfix post-8 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\" aria-label=\"Slider Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-187\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-65x65.jpg 65w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\">Slider Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-9\" class=\"post clearfix post-9 type-post status-publish format-standard has-post-thumbnail hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\" aria-label=\"Split Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-188\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-300x300.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-768x768.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-365x365.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-265x265.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-430x430.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-370x370.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742.jpg 1200w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\">Split Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-10\" class=\"post clearfix post-10 type-post status-publish format-standard has-post-thumbnail hentry category-view has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-5\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\" aria-label=\"Fullwidth Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-190\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-04-26\">\n\t\t\t\t\t<span class=\"year\">April 26, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\">Fullwidth Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-11\" class=\"post clearfix post-11 type-post status-publish format-standard has-post-thumbnail hentry category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\" aria-label=\"Left Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-191\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\">Left Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-12\" class=\"post clearfix post-12 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\" aria-label=\"Right Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-192\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-150x150.jpg 150w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\">Right Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"overlay\" class=\"themify_builder_row module_row clearfix repeat tb_section-overlay module_row_3 themify_builder_66_row module_row_66-3 tb_a310576\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-3-0 tb_bb8a8c4\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_e3fe688  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Overlay Grid4<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_46b88fb \">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  grid4 overlay masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-189\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-8\" class=\"post clearfix post-8 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\" aria-label=\"Slider Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-187\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-65x65.jpg 65w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\">Slider Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-9\" class=\"post clearfix post-9 type-post status-publish format-standard has-post-thumbnail hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\" aria-label=\"Split Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-188\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-300x300.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-768x768.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-365x365.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-265x265.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-430x430.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-370x370.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742.jpg 1200w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\">Split Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-10\" class=\"post clearfix post-10 type-post status-publish format-standard has-post-thumbnail hentry category-view has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-5\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\" aria-label=\"Fullwidth Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-190\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-04-26\">\n\t\t\t\t\t<span class=\"year\">April 26, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\">Fullwidth Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-11\" class=\"post clearfix post-11 type-post status-publish format-standard has-post-thumbnail hentry category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\" aria-label=\"Left Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-191\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\">Left Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-12\" class=\"post clearfix post-12 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\" aria-label=\"Right Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-192\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-150x150.jpg 150w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\">Right Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"polaroid\" class=\"themify_builder_row module_row clearfix repeat tb_section-polaroid module_row_4 themify_builder_66_row module_row_66-4 tb_8e8baf6\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-4-0 tb_9cb1e86\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_84f33f9  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Polaroid Grid3<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_b1f7146 \">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  grid3 polaroid masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-365x250.jpg\" width=\"365\" height=\"250\" class=\" wp-post-image wp-image-189\" alt=\"\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"grayscale\" class=\"themify_builder_row module_row clearfix repeat tb_section-grayscale module_row_5 themify_builder_66_row module_row_66-5 tb_14e4efa\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-5-0 tb_af8e2cf\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_09893bf  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Grid2 Grayscale<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_b8a3b14 filter-grayscale filter-hover-none\">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  grid2 masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"masonry\" class=\"themify_builder_row module_row clearfix repeat tb_section-masonry module_row_6 themify_builder_66_row module_row_66-6 tb_379c38c\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-6-0 tb_08f8a4b\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_5ddd901  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Masonry Grid4 Grayscale Boxed<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_54b6d40 filter-grayscale filter-hover-none\">\n        <ul class=\"post-filter\">\t<li class=\"cat-item cat-item-2\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/blog\/\">Blog<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-1\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/non-classe\/\">Non class\u00e9<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-4\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/blog\/photography\/\">Photography<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-54\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/blog\/travel\/\">Travel<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-5\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/blog\/view\/\">View<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-6\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/blog\/work\/\">Work<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-61\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/category\/z_test_z\/\">z_test_z<\/a>\n<\/li>\n<\/ul>        <div class=\"builder-posts-wrap clearfix loops-wrapper  grid4 boxed masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-265x198.jpg\" width=\"265\" class=\" wp-post-image wp-image-189\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-265x198.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-300x225.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-768x576.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-800x600.jpg 800w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-365x273.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-430x322.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-370x277.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66.jpg 1440w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-8\" class=\"post clearfix post-8 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\" aria-label=\"Slider Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-265x231.jpg\" width=\"265\" class=\" wp-post-image wp-image-187\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-265x231.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-300x262.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-365x318.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-430x375.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-370x322.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1.jpg 447w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\">Slider Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-9\" class=\"post clearfix post-9 type-post status-publish format-standard has-post-thumbnail hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\" aria-label=\"Split Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-265x265.jpg\" width=\"265\" class=\" wp-post-image wp-image-188\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-265x265.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-300x300.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-768x768.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-365x365.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-430x430.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-370x370.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742.jpg 1200w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\">Split Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-10\" class=\"post clearfix post-10 type-post status-publish format-standard has-post-thumbnail hentry category-view has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-5\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\" aria-label=\"Fullwidth Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-265x175.jpg\" width=\"265\" class=\" wp-post-image wp-image-190\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-265x175.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-300x199.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-768x509.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-365x241.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-430x284.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-180x120.jpg 180w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-370x245.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553.jpg 1200w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-04-26\">\n\t\t\t\t\t<span class=\"year\">April 26, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\">Fullwidth Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-11\" class=\"post clearfix post-11 type-post status-publish format-standard has-post-thumbnail hentry category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\" aria-label=\"Left Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-265x176.jpg\" width=\"265\" class=\" wp-post-image wp-image-191\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-265x176.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-300x200.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-768x512.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-365x243.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-430x286.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-270x180.jpg 270w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-180x120.jpg 180w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-370x246.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3.jpg 1200w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\">Left Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-12\" class=\"post clearfix post-12 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\" aria-label=\"Right Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-265x397.jpg\" width=\"265\" class=\" wp-post-image wp-image-192\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-265x397.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-200x300.jpg 200w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-768x1152.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024.jpg 683w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-365x547.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-430x645.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-370x555.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401.jpg 1400w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\">Right Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"sepia\" class=\"themify_builder_row module_row clearfix repeat tb_section-sepia module_row_7 themify_builder_66_row module_row_66-7 tb_b4c9c52\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-7-0 tb_1798654\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_b2cca62  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Grid4 No-Gutter Overlay Sepia<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_d72d986 filter-sepia filter-hover-none\">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  grid4 overlay no-gutter masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-189\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-8\" class=\"post clearfix post-8 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\" aria-label=\"Slider Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-187\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-65x65.jpg 65w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\">Slider Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-9\" class=\"post clearfix post-9 type-post status-publish format-standard has-post-thumbnail hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\" aria-label=\"Split Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-188\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-300x300.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-768x768.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-365x365.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-265x265.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-430x430.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-370x370.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742.jpg 1200w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\">Split Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-10\" class=\"post clearfix post-10 type-post status-publish format-standard has-post-thumbnail hentry category-view has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-5\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\" aria-label=\"Fullwidth Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-190\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-04-26\">\n\t\t\t\t\t<span class=\"year\">April 26, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\">Fullwidth Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-11\" class=\"post clearfix post-11 type-post status-publish format-standard has-post-thumbnail hentry category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\" aria-label=\"Left Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-191\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-47x48.jpg 47w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\">Left Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-12\" class=\"post clearfix post-12 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\" aria-label=\"Right Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\"><img loading=\"lazy\" src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-290x290.jpg\" width=\"290\" height=\"290\" class=\" wp-post-image wp-image-192\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-150x150.jpg 150w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\">Right Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t\t<!-- module_row -->\n\t<div   data-anchor=\"masonry-no-gutter\" class=\"themify_builder_row module_row clearfix repeat tb_section-masonry-no-gutter module_row_8 themify_builder_66_row module_row_66-8 tb_130fed2\">\n\t    \t    <div class=\"row_inner col_align_top\" >\n\t\t\t<div  class=\"module_column tb-column col-full first tb_66_column module_column_0 module_column_66-8-0 tb_5a030c6\">\n\t    \t    \t        <div class=\"tb-column-inner\">\n\t\t    <!-- module text -->\n<div  class=\"module module-text tb_121edd6  repeat  \">\n            <div  class=\"tb_text_wrap\">\n    <h3>Masonry Grid3 Grayscale Overlay No-gutter<\/h3>    <\/div>\n<\/div>\n<!-- \/module text -->\n    <!-- module post -->\n    <div  class=\"module module-post tb_7f25eca filter-grayscale filter-hover-none\">\n                <div class=\"builder-posts-wrap clearfix loops-wrapper  grid3 overlay no-gutter masonry\">\n            \n\n<article id=\"post-2363\" class=\"post clearfix post-2363 type-post status-publish format-standard hentry category-travel category-z_test_z tag-z_test-tag_k has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-54  cat-61\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\" aria-label=\"z_test_003-post\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-11-10\">\n\t\t\t\t\t<span class=\"year\">November 10, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/11\/10\/z_test_003-post\/\">z_test_003-post<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-1\" class=\"post clearfix post-1 type-post status-publish format-standard hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\" aria-label=\"Bonjour tout le monde\u00a0!\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2020-09-28\">\n\t\t\t\t\t<span class=\"year\">September 28, 2020<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2020\/09\/28\/bonjour-tout-le-monde\/\">Bonjour tout le monde\u00a0!<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-7\" class=\"post clearfix post-7 type-post status-publish format-standard has-post-thumbnail hentry category-blog has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-2\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\" aria-label=\"Gallery Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-430x322.jpg\" width=\"430\" class=\" wp-post-image wp-image-189\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-430x322.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-300x225.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-768x576.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-800x600.jpg 800w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-365x273.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-265x198.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66-1024x768-370x277.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/demoimage66.jpg 1440w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-07\">\n\t\t\t\t\t<span class=\"year\">June 7, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/07\/gallery-layout\/\">Gallery Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-8\" class=\"post clearfix post-8 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\" aria-label=\"Slider Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-430x375.jpg\" width=\"430\" class=\" wp-post-image wp-image-187\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-430x375.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-300x262.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-365x318.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-265x231.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1-370x322.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/ultra-masonry-7-1.jpg 447w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/slider-layout\/\">Slider Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-9\" class=\"post clearfix post-9 type-post status-publish format-standard has-post-thumbnail hentry category-non-classe has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-1\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\" aria-label=\"Split Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-430x430.jpg\" width=\"430\" class=\" wp-post-image wp-image-188\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-430x430.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-150x150.jpg 150w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-300x300.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-768x768.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-365x365.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-290x290.jpg 290w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-265x265.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-65x65.jpg 65w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-50x50.jpg 50w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742-1024x1024-370x370.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/99811742.jpg 1200w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-06-06\">\n\t\t\t\t\t<span class=\"year\">June 6, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/06\/06\/split-layout\/\">Split Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-10\" class=\"post clearfix post-10 type-post status-publish format-standard has-post-thumbnail hentry category-view has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-5\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\" aria-label=\"Fullwidth Layout\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-430x284.jpg\" width=\"430\" class=\" wp-post-image wp-image-190\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-430x284.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-300x199.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-768x509.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-365x241.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-265x175.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-180x120.jpg 180w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553-1024x678-370x245.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/188185553.jpg 1200w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2016-04-26\">\n\t\t\t\t\t<span class=\"year\">April 26, 2016<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2016\/04\/26\/fullwidth-layout\/\">Fullwidth Layout<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-11\" class=\"post clearfix post-11 type-post status-publish format-standard has-post-thumbnail hentry category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\" aria-label=\"Left Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-430x286.jpg\" width=\"430\" class=\" wp-post-image wp-image-191\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-430x286.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-300x200.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-768x512.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-365x243.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-265x176.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-270x180.jpg 270w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-180x120.jpg 180w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3-1024x683-370x246.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/model-3.jpg 1200w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/left-sidebar\/\">Left Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-12\" class=\"post clearfix post-12 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\" aria-label=\"Right Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-430x645.jpg\" width=\"430\" class=\" wp-post-image wp-image-192\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-430x645.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-200x300.jpg 200w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-768x1152.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024.jpg 683w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-365x547.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-265x397.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401-683x1024-370x555.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/43e390401.jpg 1400w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/right-sidebar\/\">Right Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-13\" class=\"post clearfix post-13 type-post status-publish format-standard has-post-thumbnail hentry category-photography has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/classic-fullwidth\/\" aria-label=\"Classic Fullwidth\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/classic-fullwidth\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-430x286.jpg\" width=\"430\" class=\" wp-post-image wp-image-193\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-430x286.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-300x200.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-768x512.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-365x243.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-265x176.jpg 265w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-270x180.jpg 270w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-180x120.jpg 180w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2-1024x682-370x246.jpg 370w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/2e9b0cb2.jpg 1400w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/classic-fullwidth\/\">Classic Fullwidth<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n\n\n<article id=\"post-14\" class=\"post clearfix post-14 type-post status-publish format-standard has-post-thumbnail hentry category-photography category-work has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author   cat-4  cat-6\">\n\t\n            <a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/fullwidth-with-sidebar\/\" aria-label=\"Fullwidth With Sidebar\" data-post-permalink=\"yes\" style=\"display: none;\"><\/a>\n    \n\t\n\t\n\t\n\t\t\n\t\t\t<figure class=\"post-image  clearfix\">\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/fullwidth-with-sidebar\/\"><img src=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311-1024x1009-430x423.jpg\" width=\"430\" class=\" wp-post-image wp-image-194\" alt=\"\" srcset=\"https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311-1024x1009-430x423.jpg 430w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311-300x296.jpg 300w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311-768x757.jpg 768w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311-1024x1009.jpg 1024w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311-1024x1009-365x359.jpg 365w, https:\/\/rivierasun-properties.com\/wp-content\/uploads\/2020\/09\/88274311.jpg 1200w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a>\n\t\t\t\t\n\t\t\t<\/figure>\n\n\t\t\n\t\n\t\n\t<div class=\"post-content\">\n\t\t<div class=\"post-content-inner\">\n\n\t\t\t\t\t\t\t\t<div class=\"post-date-wrap post-date-inline\">\n\t\t<time class=\"post-date entry-date updated\" datetime=\"2015-04-09\">\n\t\t\t\t\t<span class=\"year\">April 9, 2015<\/span>\n\t\t\t\t<\/time>\n\t<\/div><!-- .post-date-wrap -->\n\t\t\t\t\n\t\t\t\t\t\t\t <h2 class=\"post-title entry-title\"><a href=\"https:\/\/rivierasun-properties.com\/index.php\/2015\/04\/09\/fullwidth-with-sidebar\/\">Fullwidth With Sidebar<\/a> <\/h2>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"entry-content\">\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><!-- \/.entry-content -->\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- \/.post-content-inner -->\n\t<\/div>\n\t<!-- \/.post-content -->\n\t\n<\/article>\n<!-- \/.post -->\n        <\/div><!-- .builder-posts-wrap -->\n                    <\/div>\n    <!-- \/module post -->\n\n\t        <\/div>\n\t    \t<\/div>\n\t\t    <\/div>\n\t    <!-- \/row_inner -->\n\t<\/div>\n\t<!-- \/module_row -->\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Auto Tiles<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":60,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"builder_content":"<h3>Auto Tiles<\/h3>\n\n<h3>List Post<\/h3>\n\n<h3>Flip Grid4<\/h3>\n\n<h3>Overlay Grid4<\/h3>\n\n<h3>Polaroid Grid3<\/h3>\n\n<h3>Grid2 Grayscale<\/h3>\n\n<h3>Masonry Grid4 Grayscale Boxed<\/h3>\n\n<h3>Grid4 No-Gutter Overlay Sepia<\/h3>\n\n<h3>Masonry Grid3 Grayscale Overlay No-gutter<\/h3>\n","_links":{"self":[{"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/pages\/66"}],"collection":[{"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":2,"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/pages\/66\/revisions"}],"predecessor-version":[{"id":2016,"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/pages\/66\/revisions\/2016"}],"up":[{"embeddable":true,"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/pages\/60"}],"wp:attachment":[{"href":"https:\/\/rivierasun-properties.com\/index.php\/wp-json\/wp\/v2\/media?parent=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}